{"id":14329,"date":"2023-02-02T19:35:55","date_gmt":"2023-02-02T19:35:55","guid":{"rendered":"https:\/\/massive.rupertport.com\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/"},"modified":"2024-04-09T13:49:22","modified_gmt":"2024-04-09T21:49:22","slug":"lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour","status":"publish","type":"post","link":"https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/","title":{"rendered":"L&rsquo;APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">L&rsquo;APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">2 f\u00e9vrier 2023<\/h4>\n\n\n\n<p>Deux \u00e9tablissements de soins de sant\u00e9 de la c\u00f4te nord &#8211; l&rsquo;h\u00f4pital r\u00e9gional de Prince Rupert et le manoir Acropolis &#8211; sont \u00e9quip\u00e9s de 61 nouveaux lits d&rsquo;h\u00f4pital, ce qui am\u00e9liore consid\u00e9rablement le niveau de confort et d&rsquo;accessibilit\u00e9 pour les patients, les r\u00e9sidents des \u00e9tablissements de soins de longue dur\u00e9e et le personnel. Les lits ont \u00e9t\u00e9 remplac\u00e9s gr\u00e2ce \u00e0 un partenariat entre le fonds d&rsquo;investissement communautaire de l&rsquo;administration portuaire de Prince Rupert (PRPA) et la North Coast Health Improvement Society (NCHIS), dans le cadre des efforts continus des deux organisations pour am\u00e9liorer la qualit\u00e9 des soins de sant\u00e9 pour les personnes vivant dans la r\u00e9gion.<\/p>\n\n\n\n<p>Les nouveaux lits d&rsquo;h\u00f4pitaux offrent une s\u00e9rie de caract\u00e9ristiques qui les rendent plus s\u00fbrs, plus efficaces et capables d&rsquo;accueillir des personnes ayant des besoins physiques tr\u00e8s vari\u00e9s. \u00c9quip\u00e9s de deux jeux de commandes, les lits s&rsquo;abaissent facilement au sol, ce qui permet d&rsquo;\u00e9viter les chutes lorsque les patients entrent et sortent du lit. Inversement, les lits s&rsquo;\u00e9l\u00e8vent \u00e9galement pour s&rsquo;adapter \u00e0 la taille du personnel soignant, ce qui r\u00e9duit le nombre de l\u00e9sions dues au stress r\u00e9p\u00e9titif subies lors des soins aux patients. En outre, un seul m\u00e9canisme est n\u00e9cessaire pour verrouiller les lits en place, alors que les anciens lits n\u00e9cessitaient quatre verrous distincts pour les emp\u00eacher de bouger. Les nouveaux lits sont \u00e9galement facilement r\u00e9glables et peuvent accueillir deux tailles de matelas diff\u00e9rentes, afin de r\u00e9pondre au mieux aux besoins du patient.<\/p>\n\n\n\n<p>\u00ab\u00a0Ce projet contribue \u00e0 la modernisation de nos \u00e9tablissements de sant\u00e9 locaux, permet d&rsquo;am\u00e9liorer la qualit\u00e9 des soins prodigu\u00e9s aux patients de notre communaut\u00e9 et am\u00e9liore l&rsquo;environnement de travail du personnel d\u00e9vou\u00e9 qui dispense ces soins\u00a0\u00bb, a d\u00e9clar\u00e9 Shaun Stevenson, pr\u00e9sident-directeur g\u00e9n\u00e9ral de l&rsquo;Administration portuaire de Prince Rupert.<\/p>\n\n\n\n<p>\u00ab\u00a0Le projet de remplacement des lits n&rsquo;aurait pas \u00e9t\u00e9 possible sans le soutien g\u00e9n\u00e9reux du fonds d&rsquo;investissement communautaire de l&rsquo;administration portuaire de Prince Rupert, qui s&rsquo;inscrit parfaitement dans nos efforts d&rsquo;achat d&rsquo;\u00e9quipement et de soutien aux programmes qui am\u00e9liorent la sant\u00e9 et le bien-\u00eatre des habitants de notre r\u00e9gion\u00a0\u00bb, a d\u00e9clar\u00e9 Stefan Delloch, pr\u00e9sident de la North Coast Health Improvement Society.<\/p>\n\n\n\n<p>Le Fonds d&rsquo;investissement communautaire de l&rsquo;APPR a fourni 150 000 dollars pour ce projet de 300 000 dollars. DP World Prince Rupert a \u00e9galement contribu\u00e9 \u00e0 ce total. Au cours des dix derni\u00e8res ann\u00e9es, l&rsquo;APPR a consacr\u00e9 plus de 570 000 dollars \u00e0 des projets qui am\u00e9liorent et modernisent l&rsquo;h\u00f4pital r\u00e9gional de Prince Rupert et le manoir Acropolis :<\/p>\n\n\n\n<p>&#8211; Unit\u00e9 de soins am\u00e9lior\u00e9s contre le cancer : 100 000<br>&#8211; Guide de d\u00e9pistage du cancer : $35,260<br>&#8211; Remplacement de l&rsquo;appareil de radiologie : 69 750<br>&#8211; Mat\u00e9riel chirurgical orthop\u00e9dique : 60 500<br>&#8211; Am\u00e9lioration de la baignoire des patients hospitalis\u00e9s : 45 500<br>&#8211; Modernisation de l&rsquo;appareil d&rsquo;\u00e9chographie diagnostique : 72 500<br>&#8211; Am\u00e9lioration des soins palliatifs : 36 500<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-174-1024x768.jpg\" alt=\"\" class=\"wp-image-9703\" srcset=\"https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-174-1024x768.jpg 1024w, https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-174-300x225.jpg 300w, https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-174-768x576.jpg 768w, https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-174-1536x1152.jpg 1536w, https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-174.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-172-1024x768.jpg\" alt=\"\" class=\"wp-image-9702\" srcset=\"https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-172-1024x768.jpg 1024w, https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-172-300x225.jpg 300w, https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-172-768x576.jpg 768w, https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-172-1536x1152.jpg 1536w, https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-172.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"padding:56.25% 0 0 0;position:relative;\"><iframe src=\"https:\/\/player.vimeo.com\/video\/795352108?h=f503314650&#038;badge=0&#038;autopause=0&#038;player_id=0&#038;app_id=58479\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen=\"\" style=\"position:absolute;top:0;left:0;width:100%;height:100%;\" title=\"Le plus gros investissement de l'APPR dans le secteur de la sant\u00e9 locale \u00e0 ce jour\"><\/iframe><\/div><script src=\"https:\/\/player.vimeo.com\/api\/player.js\"><\/script>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour 2 f\u00e9vrier 2023 Deux \u00e9tablissements de soins de sant\u00e9 de la c\u00f4te nord &#8211; l&rsquo;h\u00f4pital r\u00e9gional de Prince Rupert et le manoir Acropolis &#8211; sont \u00e9quip\u00e9s de 61 nouveaux lits d&rsquo;h\u00f4pital, ce qui am\u00e9liore consid\u00e9rablement le niveau de confort [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13596,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[44],"tags":[],"class_list":["post-14329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour | Autorit\u00e9 portuaire de Prince Rupert<\/title>\n<meta name=\"description\" content=\"L&#039;APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour 2 f\u00e9vrier 2023 Deux \u00e9tablissements de soins de sant\u00e9 de la c\u00f4te\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour | Autorit\u00e9 portuaire de Prince Rupert\" \/>\n<meta property=\"og:description\" content=\"L&#039;APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour 2 f\u00e9vrier 2023 Deux \u00e9tablissements de soins de sant\u00e9 de la c\u00f4te\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/\" \/>\n<meta property=\"og:site_name\" content=\"Autorit\u00e9 portuaire de Prince Rupert\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rupertport\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-02T19:35:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-09T21:49:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-174-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"457\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"kvoigt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rupertport\" \/>\n<meta name=\"twitter:site\" content=\"@rupertport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\\\/\"},\"author\":{\"name\":\"kvoigt\",\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/#\\\/schema\\\/person\\\/1eeff0dbbd2c7b9aca4c07c38a801b92\"},\"headline\":\"L&rsquo;APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour\",\"datePublished\":\"2023-02-02T19:35:55+00:00\",\"dateModified\":\"2024-04-09T21:49:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\\\/\"},\"wordCount\":561,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rupertport.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MicrosoftTeams-image-174-1.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\\\/\",\"url\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\\\/\",\"name\":\"L'APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour | Autorit\u00e9 portuaire de Prince Rupert\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rupertport.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MicrosoftTeams-image-174-1.jpg\",\"datePublished\":\"2023-02-02T19:35:55+00:00\",\"dateModified\":\"2024-04-09T21:49:22+00:00\",\"description\":\"L'APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour 2 f\u00e9vrier 2023 Deux \u00e9tablissements de soins de sant\u00e9 de la c\u00f4te\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rupertport.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MicrosoftTeams-image-174-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rupertport.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MicrosoftTeams-image-174-1.jpg\",\"width\":2048,\"height\":457},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/page-de-garde\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/\",\"name\":\"Prince Rupert Port Authority\",\"description\":\"L'avant-garde du Canada\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/#organization\"},\"alternateName\":\"PRPA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/#organization\",\"name\":\"Prince Rupert Port Authority\",\"alternateName\":\"PRPA\",\"url\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rupertport.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cropped-PRPA-logo-meta-1200x1200-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rupertport.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cropped-PRPA-logo-meta-1200x1200-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Prince Rupert Port Authority\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rupertport\\\/\",\"https:\\\/\\\/x.com\\\/rupertport\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rupertport.com\\\/fr\\\/#\\\/schema\\\/person\\\/1eeff0dbbd2c7b9aca4c07c38a801b92\",\"name\":\"kvoigt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee21931e6e17ca4de48750854755ae1c662578d5a748b376b291e61a3d6c7802?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee21931e6e17ca4de48750854755ae1c662578d5a748b376b291e61a3d6c7802?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee21931e6e17ca4de48750854755ae1c662578d5a748b376b291e61a3d6c7802?s=96&d=mm&r=g\",\"caption\":\"kvoigt\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour | Autorit\u00e9 portuaire de Prince Rupert","description":"L'APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour 2 f\u00e9vrier 2023 Deux \u00e9tablissements de soins de sant\u00e9 de la c\u00f4te","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/","og_locale":"fr_FR","og_type":"article","og_title":"L'APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour | Autorit\u00e9 portuaire de Prince Rupert","og_description":"L'APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour 2 f\u00e9vrier 2023 Deux \u00e9tablissements de soins de sant\u00e9 de la c\u00f4te","og_url":"https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/","og_site_name":"Autorit\u00e9 portuaire de Prince Rupert","article_publisher":"https:\/\/www.facebook.com\/rupertport\/","article_published_time":"2023-02-02T19:35:55+00:00","article_modified_time":"2024-04-09T21:49:22+00:00","og_image":[{"width":2048,"height":457,"url":"https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-174-1.jpg","type":"image\/jpeg"}],"author":"kvoigt","twitter_card":"summary_large_image","twitter_creator":"@rupertport","twitter_site":"@rupertport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/#article","isPartOf":{"@id":"https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/"},"author":{"name":"kvoigt","@id":"https:\/\/www.rupertport.com\/fr\/#\/schema\/person\/1eeff0dbbd2c7b9aca4c07c38a801b92"},"headline":"L&rsquo;APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour","datePublished":"2023-02-02T19:35:55+00:00","dateModified":"2024-04-09T21:49:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/"},"wordCount":561,"publisher":{"@id":"https:\/\/www.rupertport.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-174-1.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/","url":"https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/","name":"L'APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour | Autorit\u00e9 portuaire de Prince Rupert","isPartOf":{"@id":"https:\/\/www.rupertport.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/#primaryimage"},"image":{"@id":"https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-174-1.jpg","datePublished":"2023-02-02T19:35:55+00:00","dateModified":"2024-04-09T21:49:22+00:00","description":"L'APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour 2 f\u00e9vrier 2023 Deux \u00e9tablissements de soins de sant\u00e9 de la c\u00f4te","breadcrumb":{"@id":"https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/#primaryimage","url":"https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-174-1.jpg","contentUrl":"https:\/\/www.rupertport.com\/wp-content\/uploads\/2023\/02\/MicrosoftTeams-image-174-1.jpg","width":2048,"height":457},{"@type":"BreadcrumbList","@id":"https:\/\/www.rupertport.com\/fr\/lappr-realise-son-plus-gros-investissement-local-dans-le-domaine-de-la-sante-a-ce-jour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rupertport.com\/fr\/page-de-garde\/"},{"@type":"ListItem","position":2,"name":"L&#8217;APPR r\u00e9alise son plus gros investissement local dans le domaine de la sant\u00e9 \u00e0 ce jour"}]},{"@type":"WebSite","@id":"https:\/\/www.rupertport.com\/fr\/#website","url":"https:\/\/www.rupertport.com\/fr\/","name":"Prince Rupert Port Authority","description":"L'avant-garde du Canada","publisher":{"@id":"https:\/\/www.rupertport.com\/fr\/#organization"},"alternateName":"PRPA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rupertport.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.rupertport.com\/fr\/#organization","name":"Prince Rupert Port Authority","alternateName":"PRPA","url":"https:\/\/www.rupertport.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rupertport.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.rupertport.com\/wp-content\/uploads\/2021\/04\/cropped-PRPA-logo-meta-1200x1200-1.jpg","contentUrl":"https:\/\/www.rupertport.com\/wp-content\/uploads\/2021\/04\/cropped-PRPA-logo-meta-1200x1200-1.jpg","width":512,"height":512,"caption":"Prince Rupert Port Authority"},"image":{"@id":"https:\/\/www.rupertport.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rupertport\/","https:\/\/x.com\/rupertport"]},{"@type":"Person","@id":"https:\/\/www.rupertport.com\/fr\/#\/schema\/person\/1eeff0dbbd2c7b9aca4c07c38a801b92","name":"kvoigt","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ee21931e6e17ca4de48750854755ae1c662578d5a748b376b291e61a3d6c7802?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ee21931e6e17ca4de48750854755ae1c662578d5a748b376b291e61a3d6c7802?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ee21931e6e17ca4de48750854755ae1c662578d5a748b376b291e61a3d6c7802?s=96&d=mm&r=g","caption":"kvoigt"}}]}},"_links":{"self":[{"href":"https:\/\/www.rupertport.com\/fr\/wp-json\/wp\/v2\/posts\/14329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rupertport.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rupertport.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rupertport.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rupertport.com\/fr\/wp-json\/wp\/v2\/comments?post=14329"}],"version-history":[{"count":2,"href":"https:\/\/www.rupertport.com\/fr\/wp-json\/wp\/v2\/posts\/14329\/revisions"}],"predecessor-version":[{"id":18863,"href":"https:\/\/www.rupertport.com\/fr\/wp-json\/wp\/v2\/posts\/14329\/revisions\/18863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rupertport.com\/fr\/wp-json\/wp\/v2\/media\/13596"}],"wp:attachment":[{"href":"https:\/\/www.rupertport.com\/fr\/wp-json\/wp\/v2\/media?parent=14329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rupertport.com\/fr\/wp-json\/wp\/v2\/categories?post=14329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rupertport.com\/fr\/wp-json\/wp\/v2\/tags?post=14329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}